{"id":24397,"date":"2024-12-31T20:33:54","date_gmt":"2024-12-31T19:33:54","guid":{"rendered":"https:\/\/www.kulturwelten.at\/dozenten-musikverein-wien\/"},"modified":"2026-02-23T19:43:33","modified_gmt":"2026-02-23T18:43:33","slug":"dozenten-musikverein-wien","status":"publish","type":"page","link":"https:\/\/www.kulturwelten.at\/de\/dozenten-musikverein-wien\/","title":{"rendered":"Dozenten Musikverein Wien"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"24397\" class=\"elementor elementor-24397 elementor-21157\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58641c1 e-con-full e-flex e-con e-parent\" data-id=\"58641c1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f43fa1 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5f43fa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kulturwelten Sommerakademie 2026<br><br>Musikverein Wien<br>6 - 11 July<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2923980 e-flex e-con-boxed e-con e-parent\" data-id=\"2923980\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37a5b28 elementor-widget elementor-widget-html\" data-id=\"37a5b28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"music-bg\">\n  <div class=\"note note-1\">\u2669<\/div>\n  <div class=\"note note-2\">\ud834\udd1e<\/div> <div class=\"note note-3\">\u266b<\/div>\n  <div class=\"note note-4\">\ud834\udd22<\/div> <div class=\"note note-5\">\u266a<\/div>\n  <div class=\"note note-6\">\ud834\udd21<\/div> <div class=\"note note-7\">\u266c<\/div>\n  <div class=\"note note-8\">\ud834\udd1e<\/div> <div class=\"note note-9\">\u266b<\/div>\n  <div class=\"note note-10\">\ud834\udd22<\/div> <div class=\"note note-11\">\u2669<\/div>\n  <div class=\"note note-12\">\u266a<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d3db10 animated-slow elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"7d3db10\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Dozent:innen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b4455e elementor-widget elementor-widget-menu-anchor\" data-id=\"6b4455e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"TOP\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b47a058 elementor-widget__width-inherit animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b47a058\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"#Nakajima\">Akiko Nakajima, Gesang<\/a><\/p><p><a href=\"#Woldrich\">Maria Woldrich, Gesang<\/a><\/p><p><a href=\"#Copons-Labarias\">Elena Copons-Labarias, Gesang<\/a><\/p><p><a href=\"#Haffner\">Eszter Haffner, Violine &amp; Viola<\/a><\/p><p><a href=\"#Falger\">Dominika Falger, Violine<\/a><\/p><p><a href=\"#Kless\">Yair Kless, Violine<\/a><\/p><p><a href=\"#Gahl\">Annelie Gahl, Violine<\/a><\/p><p><a href=\"#Winokurow\">Wladislaw Winokurow, Violine<\/a><\/p><p><a href=\"#Brand\">Regina Brandst\u00e4tter, Violine<\/a><\/p><p><a href=\"#Kalisch\">Andrei Kalisch, Violine<\/a><\/p><p><a href=\"#Tichonow\">Stanislaw Tichonow, Klavier<\/a><\/p><p><a href=\"#Gulda\">Paul Gulda, Klavier<\/a><\/p><p><a href=\"#Kharin\">Vladimir Kharin, Klavier<\/a><\/p><p><a href=\"#Fliedl\">Jeremias Fliedl, Violoncello<\/a><\/p><p><a href=\"#Zelenin\">Konstantin Zelenin, Violoncello<\/a><\/p><p><a href=\"#Kitanovic\">Ivan Kitanovi\u0107, Kontrabass<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b623e18 animated-slow e-con-full e-flex elementor-invisible e-con e-parent\" data-id=\"b623e18\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4cb6b49 e-con-full gradient-background e-flex elementor-invisible e-con e-child\" data-id=\"4cb6b49\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-487bb41 elementor-widget elementor-widget-menu-anchor\" data-id=\"487bb41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Nakajima\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b02a4e4 elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b02a4e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Akiko Nakajima, Gesang<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54e7915 elementor-drop-cap-yes animated-slow elementor-widget-mobile__width-initial elementor-drop-cap-view-default elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"54e7915\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img fetchpriority=\"high\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignleft wp-image-20229\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/03\/Akiko-Nakajima-5-2.jpg?resize=305%2C457&#038;ssl=1\" alt=\"\" width=\"305\" height=\"457\">Die Karriere der japanischen Sopranistin Akiko Nakajima begann nach ihrem Sieg beim Australian Singing Competition 1991. Es folgten kurz darauf ihr Deb\u00fct an der Opera Australia in La clemenza di Tito unter Christopher Hogwood und ihr Europadeb\u00fct am Teatro di San Carlo di Napoli als Musetta in La Boh\u00e8me. Unter den 57 Opernrollen, die sie sang, sind insbesondere Lucia, Amina (La sonnambula), Violetta, Anne (The Rakes Progress), Susanna, Norina, Adina, Sophie und Pamina zu nennen. Sie trat unter renommierten Dirigenten wie Seiji Ozawa, Herbert Blomstedt, Zubin Mehta und Andre Previn auf. Zu den Opernh\u00e4usern und Theatern, in denen sie auftrat, geh\u00f6ren die Wiener Volksoper, die Hamburgische Staatsoper, die Alte Oper Frankfurt, das New National Theatre Tokyo, das Th\u00e9\u00e2tre des Champs-\u00c9lys\u00e9es, die Suntory Hall, die Avery Fisher Hall, die Walt Disney Hall, das Wiener Konzerthaus, der Wiener Musikverein und die Wigmore Hall. Akiko Nakajimas erste Solo-CD, La Pastorella, wurde f\u00fcr die Liste der Deutschen Schallplattenkritik nominiert, und auf ihre zweite Solo-CD, Female Portraits, folgte Plaisir d\u2019amour. Eine DVD-Aufzeichnung eines Live-Konzerts von Brittens \u201eEin Sommernachtstraum\u201c mit Seiji Ozawa wurde von NHK Enterprise dokumentiert, gefolgt von \u201eWien, du Stadt meiner Tr\u00e4ume\u201c, das vom Wiener Label Gramola im Musikverein aufgenommen wurde. Als Generaldirektorin der Noura Opera Foundation in Japan und Professorin an der Universit\u00e4t f\u00fcr Musik und darstellende Kunst der Stadt Wien pr\u00e4gt Nakajima weiterhin die weltweite Opern- und Vokalkonzertszene nachhaltig.       <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-185cb7f #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"185cb7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a10a459 e-con-full gradient-background2 e-flex elementor-invisible e-con e-child\" data-id=\"a10a459\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-992933e elementor-widget elementor-widget-menu-anchor\" data-id=\"992933e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Woldrich\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-015c7a0 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"015c7a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Maria Woldrich, Gesang<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d9f007 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9d9f007\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" data-recalc-dims=\"1\" class=\"alignleft wp-image-18587\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2023\/03\/WoldrichMaria_02.jpgBild-e1677976284198-500x422.jpg?resize=520%2C438&#038;ssl=1\" alt=\"\" width=\"520\" height=\"438\" srcset=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2023\/03\/WoldrichMaria_02.jpgBild-e1677976284198.jpg?resize=500%2C422&amp;ssl=1 500w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2023\/03\/WoldrichMaria_02.jpgBild-e1677976284198.jpg?resize=768%2C648&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2023\/03\/WoldrichMaria_02.jpgBild-e1677976284198.jpg?resize=800%2C675&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2023\/03\/WoldrichMaria_02.jpgBild-e1677976284198.jpg?w=982&amp;ssl=1 982w\" sizes=\"(max-width: 520px) 100vw, 520px\" \/><span style=\"color: #ffffff;\">Maria Woldrich wurde in Deutschland geboren und studierte Kirchenmusik, Klavier und Gesangsp\u00e4dagogik sowie Konzertgesang an der Hochschule f\u00fcr Kirchenmusik &amp; Musikp\u00e4dagogik in Regensburg, an der Musikhochschule in M\u00fcnchen und in Wien. Zu ihren Lehrern z\u00e4hlen Peter Wetzler, Sch\u00fcler von Paul Lohmann, Franz Lukasovsky, Rotraud Hansmann, Walter Berry und Christina Baader. In Bayern unterrichtete sie Klavier bei den \u201eRegensburger Domspatzen\u201c sowie Gesang und Klavier an der \u201eBerufsfachschule f\u00fcr Musik\u201c in Niederbayern. Bei Norbert Faller in Wien absolvierte sie eine Ausbildung nach der Methode von Ilse Middendorf zur akademischen Atemp\u00e4dagogin. Neben Engagements an der Wiener Kammeroper, beim Wiener Rundfunkchor, beim Chor der Wiener Staatsoper und bei den Salzburger Festspielen war sie auch Solistin auf Tournee mit der Wiener Jungen Oper sowie bei Konzerten in \u00d6sterreich und im Ausland. Zwischenzeitlich unterrichtete sie Klavier und Gesang in Nieder\u00f6sterreich und Gesang an der Musikschule der Stadt Wien. Viele Jahre lang leitete sie die Abteilung \u201eJunge Akademie\u201d (F\u00f6rderung hochbegabter Musiker) f\u00fcr die Gesangsgruppe. Maria W. absolvierte zahlreiche Fortbildungen in Gesang und Gesangsp\u00e4dagogik sowie in Atem- und K\u00f6rperarbeit an der Musikschule und privat (z. B. bei M. Klaushofer, J. Bauer-Huppmann, R. Braga-Postl, U. Schwabe, Y. Khomenko, G. Kahry, K. Hanser, C. Visca, D. Fally, S. Wienhausen, N. Turner, CVT mit T. Raich, Estill Voice mit C. Morini Level 1 und 2, Rabine-Methode mit S. Eisch, Atem-Tonus-Ton mit M. H\u00f6ller-Zangenfeind, Alexander-Technik mit H. Anderson, Musikkinesiologie mit F. Karimi-Djafar-Zadeh, EFT mit M. Br\u00fcssing). Von 2017 bis 2023 hatte sie eine Lehrstelle f\u00fcr Unterrichtspraxis an der Musikuniversit\u00e4t Wien inne. Zahlreiche Sch\u00fcler ihrer Gesangsklasse haben sehr erfolgreich an den Landes- und Bundeswettbewerben Prima la Musica teilgenommen. Viele Sch\u00fcler studieren bereits an der Universit\u00e4t. M. Woldrich ist seit vielen Jahren Jurymitglied beim Prima la Musica-Wettbewerb. Seit November 2022 ist sie Vorstandsmitglied der EVTA-Austria und verantwortlich f\u00fcr Wien.           <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a9bd52 #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7a9bd52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6db4246 e-con-full gradient-background5 e-flex elementor-invisible e-con e-child\" data-id=\"6db4246\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a974db7 elementor-widget elementor-widget-menu-anchor\" data-id=\"a974db7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Copons-Labarias\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ded1bf animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9ded1bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Elena Copons-Labarias, Gesang<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9d5209 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b9d5209\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" data-recalc-dims=\"1\" class=\"wp-image-26207 alignleft\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2026\/02\/Gemini_Generated_Image_76qi4376qi4376qi-e1771423573143-1024x734.png?resize=500%2C359&#038;ssl=1\" alt=\"\" width=\"500\" height=\"359\" srcset=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2026\/02\/Gemini_Generated_Image_76qi4376qi4376qi-e1771423573143.png?resize=1024%2C734&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2026\/02\/Gemini_Generated_Image_76qi4376qi4376qi-e1771423573143.png?resize=768%2C551&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2026\/02\/Gemini_Generated_Image_76qi4376qi4376qi-e1771423573143.png?resize=600%2C430&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2026\/02\/Gemini_Generated_Image_76qi4376qi4376qi-e1771423573143.png?w=1160&amp;ssl=1 1160w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>Die spanische Sopranistin Elena Copons, die f\u00fcr ihre strahlende Stimmf\u00fchrung, ihre ausdrucksstarke Intensit\u00e4t und ihre herausragende B\u00fchnenpr\u00e4senz gefeiert wird, genie\u00dft eine aktive internationale Karriere in den Bereichen Oper, Konzert und Lied. Geboren in Terrassa, studierte sie in Barcelona bei Dolors Aldea und in Wien, wo sie ihr Studium mit cum laude abschloss. Zu ihren fr\u00fchen Erfolgen z\u00e4hlen der zweite Preis beim Internationalen Hugo-Wolf-Liederwettbewerb in Stuttgart (2007) und der Preis f\u00fcr die beste S\u00e4ngerin beim Curs Internacional de M\u00fasica Isaac Alb\u00e9niz in Camprodon (2006). Seit \u00fcber einem Jahrzehnt ist Elena Copons regelm\u00e4\u00dfig zu Gast am Gran Teatre del Liceu und am Teatro Real, wo sie sowohl in Opern als auch in Konzerten auftritt, darunter mehrere Weltpremieren. Ihr umfangreiches Opernrepertoire umfasst Mozart-Heldinnen wie Donna Elvira, Pamina und Susanna, Marzelline (Fidelio), die Titelrolle in Rusalka, Antonia (Les Contes d&#8217;Hoffmann), M\u00e9lisande (Ariane et Barbe-Bleue) Dido (Dido und Aeneas) sowie Rollen in Werken von Bellini, Vicente Mart\u00edn y Soler und Britten. Weitere internationale Engagements f\u00fchrten sie an das Stadttheater Klagenfurt, die Kammeroper Graz, die Musikwerkstatt Wien und zu Festivals wie dem Carinthischen Sommer, den Festspielen St. Margarethen, dem Festival Castell de Peralada und den Musiktheatertagen Wien. Ihre Konzertauftritte f\u00fchrten sie an bedeutende internationale Veranstaltungsorte, darunter den Wiener Musikverein, das Wiener Konzerthaus, das Theater an der Wien, den Palau de la M\u00fasica Catalana, L&#8217;Auditori und das Auditorio Nacional de M\u00fasica in Madrid sowie zu Festivals und Kulturzentren in ganz Europa, Asien und S\u00fcdamerika. Ihr breit gef\u00e4chertes symphonisches Repertoire reicht vom Barock bis zur Gegenwart und umfasst Bachs Passionen und Messe in h-Moll, H\u00e4ndels Messias, Mendelssohns Elias, Paulus und Lobgesang, Brahms&#8216; Ein deutsches Requiem, Haydns Die Sch\u00f6pfung, Mahlers Sinfonie Nr. 4 und Orchesterlieder von Richard Strauss. Sie hat mit renommierten Orchestern wie dem Dresdner Festspielorchester, den M\u00fcnchner Symphonikern, dem Wiener Kammerorchester, der Camerata Salzburg, dem RSO Wien, der Staatskapelle Weimar und I Solisti Veneti zusammengearbeitet. Zu den Dirigenten, mit denen sie zusammengearbeitet hat, geh\u00f6ren Juanjo Mena, Ivor Bolton, David Afkham, der verstorbene Claudio Scimone, St\u00e9phane Den\u00e8ve, Leopold Hager, Josep Pons, Josep Caball\u00e9-Dom\u00e8nech, Patrick Fournillier, Pablo Gonz\u00e1lez, Erwin Ortner, Dani Espasa und Antoni Ros-Marb\u00e0. Zu ihren B\u00fchnenpartnern z\u00e4hlen die Regisseure David McVicar, Laurent Pelly, Claus Guth, David Alden, Barry Kosky und Marta Pazos. Die zeitgen\u00f6ssische Musik ist ein zentraler Pfeiler ihrer k\u00fcnstlerischen T\u00e4tigkeit. Sie schuf Hauptrollen in zwei Opern von Raquel Garc\u00eda-Tom\u00e1s: Je suis narcissiste (2019) und Alexina B. (2023), die beide f\u00fcr die International Opera Awards nominiert wurden. Im Jahr 2025 trat sie im Gran Teatre del Liceu in der Weltpremiere von Antoni Ros Marb\u00e0s Benjamin at Portbou auf, wo ihre Darstellung der Asja Lacis von Kritikern und Publikum gleicherma\u00dfen gefeiert wurde. Sie hat zahlreiche weitere Werke uraufgef\u00fchrt, darunter Opern, Kantaten, Liederzyklen und Oratorien. Lieder und Kammermusik nehmen einen wichtigen Platz in ihrem Schaffen ein. Als gefragte Rezitalistin trat sie bei der Schubert\u00edada de Vilabertran, LIFE Victoria (einschlie\u00dflich der Er\u00f6ffnungsausgabe 2017), dem Delta Chamber Music Festival, den Ludwigsburger Schlossfestspielen und der Fundaci\u00f3n Juan March sowie im Holywell Music Room in Oxford, im Kingsplace in London, im Wiener Musikverein, im Arnold Schoenberg Center und in der Liederhalle in Stuttgart auf.                  Sie hat an bedeutenden monografischen Reihen wie \u201eThe Schubert Project\u201d in Gro\u00dfbritannien und \u201eDer Ganze Hugo Wolf\u201d in Deutschland teilgenommen und deb\u00fctierte am Teatro Mayor in Bogot\u00e1 an der Seite von Christoph Pr\u00e9gardien. Zu ihren regelm\u00e4\u00dfigen Konzertpartnern z\u00e4hlen renommierte Pianisten wie Roger Vignoles, Sholto Kynoch, Eduard Kutrowatz, Chihiro Gordon, Chanda VanderHart, Deirdre Brenner, Francisco Poyato, David Malet, Jordi Armengol und Marc Heredia sowie Kammerensembles wie das Eliot Quartett und die Harfenistin Abiga\u00efl Prat. Dar\u00fcber hinaus entwickelt sie interdisziplin\u00e4re Projekte, die das Vokalrepertoire im Dialog mit Theater, Literatur und Tanz erforschen, darunter das Kabarettprogramm Cabaret (2015), Mignon versus Danae (2023) und das Mozart-Projekt Mon tr\u00e8s cher p\u00e8re (2005-2006). Ihre Auftritte wurden von ORF, Radio Nacional de Espa\u00f1a, TV3, MEDICI TV, My Opera Player und Catalunya M\u00fasica \u00fcbertragen. Ihre Aufnahme von Toldr\u00e0s La rosa als llavis mit dem Orquestra Simf\u00f2nica de Barcelona i Nacional de Catalunya unter Antoni Ros-Marb\u00e0 wurde mit dem Enderrock Award f\u00fcr das beste klassische Album ausgezeichnet. Sie hat an zahlreichen CD- und DVD-Produktionen mitgewirkt und wurde als eine der herausragenden Pers\u00f6nlichkeiten der Musik f\u00fcr die Ausstellung \u201eD&#8217;ONES\u201d im Palau Robert in Barcelona ausgew\u00e4hlt. Von 2016 bis 2024 war Elena Copons Dozentin am Conservatori Superior de M\u00fasica del Liceu in Barcelona. Seit 2024 ist sie Professorin f\u00fcr Gesang an der Joseph Haydn Privathochschule in \u00d6sterreich. Ihre Meisterkurse, die sich auf fortgeschrittene Gesangstechnik, stilistische Pr\u00e4zision, Interpretation und B\u00fchnenpr\u00e4senz konzentrieren, sollen S\u00e4nger auf die Anforderungen des internationalen Berufslebens vorbereiten. Au\u00dferdem war sie Jurymitglied bei Wettbewerben wie dem Primer Palau, dem Concurs de M\u00fasica de Cambra Paper de Musica und Prima la Musica in \u00d6sterreich.         <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62c92cf #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"62c92cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0652fee e-con-full gradient-background11 e-flex elementor-invisible e-con e-child\" data-id=\"0652fee\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44e0c6d elementor-widget elementor-widget-menu-anchor\" data-id=\"44e0c6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Haffner\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-248a3ab animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"248a3ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eszter Haffner, Violine &amp; Viola<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b62c5b2 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b62c5b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"wp-image-23231 alignright\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/Kunstlerfoto-Stephan-Sappert.jpg?resize=300%2C451&#038;ssl=1\" alt=\"\" width=\"300\" height=\"451\"><\/p><p class=\"p1\">Eszter Haffner ist eine der spannendsten und angesehensten Geigerinnen unserer Zeit. Seit \u00fcber 30 Jahren begeistert sie das Publikum weltweit mit ihrem vollen Klang, ihrer herausragenden Musikalit\u00e4t und ihren sehr pers\u00f6nlichen Interpretationen. Sie arbeitet eng mit zahlreichen renommierten Dirigenten und Orchestern zusammen und ist auch als Bratschistin sehr gefragt, stets bereit, neue k\u00fcnstlerische Horizonte zu erkunden. Ihr soziales Engagement und ihr unerm\u00fcdlicher Einsatz f\u00fcr die K\u00fcnste in \u00d6sterreich wurden 2021 mit dem \u201eGoldenen Ehrenzeichen f\u00fcr Verdienste um die Republik \u00d6sterreich\u201d und 2024 mit der Goldenen Kulturmedaille der Nieder\u00f6sterreichischen Landesregierung gew\u00fcrdigt. Im Jahr 2022 wurde Eszter zur Professorin f\u00fcr Violine an der Universit\u00e4t f\u00fcr Musik und darstellende Kunst Wien (MDW) ernannt. Seit 2000 hat sie au\u00dferdem eine Professur an der K\u00f6niglich D\u00e4nischen Musikakademie in Kopenhagen und an der Universit\u00e4t f\u00fcr Musik und darstellende Kunst Graz (KUG) inne. Sie ist Gastprofessorin am Royal College of Music London, an der Sibelius-Akademie Helsinki, an der Franz-Liszt-Akademie Budapest, an der Musikhochschule Oslo und an Konservatorien in Shanghai, Peking, Tianjin und Jerusalem (JMC). Durch ihre fachkundigen Lehrvideos auf der renommierten Plattform Tonebase Violin in den USA hat sie sich international einen Namen gemacht. Eszter war Jurymitglied bei zahlreichen internationalen Violinwettbewerben, darunter: dem Spohr-Wettbewerb (Deutschland), dem Isang-Yun-Wettbewerb (Korea), Piccolo Magico Violin Competition (Italien), Andrea Postacchini Competition (Italien), Szymanowski- und Bacewicz-Wettbewerbe (Polen), LIVE Music Now Austria, Singapore Violin Competition, Brahms-Wettbewerb (\u00d6sterreich), Dubai Olympia und Khachaturian-Wettbewerb. Sie ist k\u00fcnstlerische Leiterin des Serguei-Azizian-Wettbewerbs (D\u00e4nemark). Sie hat unz\u00e4hlige Meisterkurse an renommierten Institutionen gegeben, darunter an den ber\u00fchmtesten Universit\u00e4ten wie der NYU, der Jacobs School of Music in Bloomington, der Stanford University, der Yale University, der UCLA, der USC, der USCI, der Colburn School Los Angeles (USA) und der Geidai University (Tokio, Japan). Eszter spielt auf der Violine \u201eex Hamma Segelmann\u201d von N. Bergonzi (1780), die ihr freundlicherweise von der \u00d6sterreichischen Nationalbank zur Verf\u00fcgung gestellt wurde. Ihre Saiten werden gro\u00dfz\u00fcgig von Jargar Strings und Thomastik-Infeld Wien gesponsert, ihre B\u00f6gen von Charles Shih. Ihre CD-Aufnahmen werden von NEIRO Productions, Wien, unterst\u00fctzt. Ihre neueste Aufnahme \u2013 Mozart-Violinkonzerte mit den Salzburger Solisten \u2013 wird 2025 erscheinen. Sie ist au\u00dferdem als Beraterin und k\u00fcnstlerische Beraterin f\u00fcr Live Music Now Vienna (gegr\u00fcndet von Lord Yehudi Menuhin), EMIV Vienna, CIMS und Ver\u00e3o Cl\u00e1ssico (Portugal) sowie f\u00fcr das Virtuoso Belcanto Festival in Lucca, Italien, t\u00e4tig. Als Gr\u00fcnderin und k\u00fcnstlerische Leiterin des Serguei-Azizian-Wettbewerbs in D\u00e4nemark und Jurymitglied bei zahlreichen internationalen Wettbewerben engagiert sie sich leidenschaftlich f\u00fcr die F\u00f6rderung junger Talente aus aller Welt. Sie ist Mitglied der Fakult\u00e4t des PE-F\u00f6rderkreises der Studierenden (Mannheim, Deutschland) und Professorin an der Villa Musica (Mainz, Deutschland). Seit 2017 kuratiert sie au\u00dferdem das Kunst- und Kulturprogramm der \u00f6sterreichischen Botschaft in Kopenhagen.                   Eszter ist Mitglied sowohl der Haffner Strings als auch des Haffner Trios. Sie studierte bei Prof. Gerhard Schulz, S\u00e1ndor V\u00e9gh, Philippe Hirschhorn, Joseph Gingold, Gy\u00f6rgy Kurt\u00e1g und Thomas Kakuska an den Musikakademien in Wien, Budapest, Bloomington und Utrecht. Ihr Solodeb\u00fct gab sie 1991 im Goldenen Saal des Wiener Musikvereins unter der Leitung von Karl \u00d6sterreicher. Seitdem ist sie in vielen der weltweit f\u00fchrenden Konzerts\u00e4len aufgetreten und hat zahlreiche internationale Auszeichnungen erhalten. Sie tritt regelm\u00e4\u00dfig bei Festivals rund um den Globus auf. Neben ihrem klassischen Repertoire widmet sich Eszter auch intensiv der Interpretation zeitgen\u00f6ssischer Musik. Viele Komponisten \u2013 darunter Alfred Huber, Peter E\u00f6tv\u00f6s, Aleksey Igudesman und Volker David Kirchner \u2013 haben Werke speziell f\u00fcr sie komponiert.     <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caec8a8 #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"caec8a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-19a1c11 e-con-full gradient-background3 e-flex elementor-invisible e-con e-child\" data-id=\"19a1c11\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-803b3e8 elementor-widget elementor-widget-menu-anchor\" data-id=\"803b3e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Falger\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13b8418 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"13b8418\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dominika Falger, Violine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5295f2 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"c5295f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"size-medium wp-image-20964 alignright\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/unnamed-5-2.jpg?resize=500%2C334&#038;ssl=1\" alt=\"\" width=\"500\" height=\"334\" srcset=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/unnamed-5-2.jpg?w=886&amp;ssl=1 886w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/unnamed-5-2.jpg?resize=500%2C334&amp;ssl=1 500w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/unnamed-5-2.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/unnamed-5-2.jpg?resize=600%2C400&amp;ssl=1 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p><p data-path-to-node=\"3\">Dominika Falger wurde in Krakau in eine musikalische Familie geboren und entdeckte im Alter von vier Jahren die Violine, wobei sie ihren ersten pr\u00e4gendem Unterricht von ihrem Vater erhielt. Mit zw\u00f6lf Jahren begann sie bereits ihre Solokarriere, die sie in fast alle europ\u00e4ischen L\u00e4nder sowie nach Amerika und in den Fernen Osten f\u00fchrte. Ihre umfassende musikalische Ausbildung verbindet die strenge polnische Violinschule mit der raffinierten Wiener Tradition. Sie studierte Konzertvioline an der Musikakademie in Posen bei den Professoren Jadwiga Kaliszewska und Marcin Baranowski und setzte ihre Ausbildung in \u00d6sterreich an den Musikuniversit\u00e4ten in Wien und Graz unter der Leitung von Edward Zienkowski, Yair Kless und Jan Pospichal fort. Ihr k\u00fcnstlerisches Profil vertiefte sie durch Studien in historischer Auff\u00fchrungspraxis bei Ingomar Rainer und Hiro Kurosaki sowie durch Meisterkurse bei renommierten Virtuosen wie Herman Krebbers, Shmuel Ashkenasi und Norbert Brainin. Sie schloss ihr Studium in Konzertvioline und Instrumentalp\u00e4dagogik mit dem Titel \u201eMagistra artium\u201d ab. Dominika Falgers Virtuosit\u00e4t wurde mit Preisen bei zahlreichen renommierten internationalen Wettbewerben ausgezeichnet. Zu ihren Auszeichnungen z\u00e4hlen Preise beim Zdzis\u0142aw-Jahnke-Wettbewerb (Posen), beim Rodolfo-Lipizer-Wettbewerb (Gorizia), beim Pablo-Sarasate-Wettbewerb (Pamplona), dem Johannes-Brahms-Wettbewerb (P\u00f6rtschach), dem Karol-Lipi\u0144ski- und Henryk-Wieniawski-Wettbewerb (Lublin), dem Karol-Szymanowski-Wettbewerb (\u0141\u00f3d\u017a) und dem Tadeusz-Wro\u0144ski-Wettbewerb f\u00fcr Solovioline (Warschau). Als Solistin hat sie mit einer Vielzahl renommierter Orchester zusammengearbeitet, darunter die Wiener Symphoniker, das Taegu City Symphony Orchestra, das Baltic Philharmonic Orchestra Gdansk, die Poznan Philharmonic, das Slovak Chamber Orchestra, das Chamber Orchestra \u201eWratislavia\u201d und die Lviv Virtuosi. Ihre k\u00fcnstlerische Arbeit ist durch aktive Radio-, Fernseh- und CD-Aufnahmen dokumentiert, wobei ihr Repertoire von der Barockzeit bis zu den bedeutendsten Werken der klassischen, romantischen und zeitgen\u00f6ssischen Musik reicht. Seit 1999 ist Dominika Falger als zweite Konzertmeisterin der Wiener Symphoniker eine zentrale Figur in der Wiener Orchesterlandschaft. Seit 2017 widmet sie sich als Mitglied des Gli\u00e8re-Streichquartetts auch der Kammermusik. Parallel zu ihrer Karriere als Konzertmusikerin ist sie eine leidenschaftliche P\u00e4dagogin. Ihre Lehrt\u00e4tigkeit begann sie von 1997 bis 2005 als Assistentin in der Klasse von Prof. Yair Kless an der Universit\u00e4t f\u00fcr Musik und darstellende Kunst Graz. Heute gibt sie ihr Fachwissen als Professorin an der Musik- und Kunstuniversit\u00e4t der Stadt Wien (MUK) (seit 2011) weiter und unterrichtet au\u00dferdem an der Universit\u00e4t f\u00fcr Musik und darstellende Kunst Graz und an den Musikschulen der Stadt Wien. Ihr Engagement f\u00fcr den Nachwuchs erstreckt sich auch auf die T\u00e4tigkeit als Dozentin bei verschiedenen Meisterkursen und als Jurymitglied bei internationalen Violinwettbewerben.               <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fca3ea #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8fca3ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f4d1cdb e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"f4d1cdb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e5a7d7c elementor-widget elementor-widget-menu-anchor\" data-id=\"e5a7d7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Kless\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9366691 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9366691\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Yair Kless, Violine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-256f2a8 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"256f2a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\"><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-23247\" src=\"https:\/\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/Kless_Yair3-679x1024.avif\" alt=\"\" width=\"365\" height=\"550\" srcset=\"https:\/\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/Kless_Yair3-679x1024.avif 679w, https:\/\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/Kless_Yair3-600x905.avif 600w, https:\/\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/Kless_Yair3.avif 708w\" sizes=\"(max-width: 365px) 100vw, 365px\" \/><\/span><\/span><\/p><p class=\"p1\"><span style=\"color: #ffffff;\">Der in Israel geborene Yair Kless begann schon in jungen Jahren mit dem Violinspiel. Er absolvierte die Tel Aviv Music Academy unter der Leitung von Israel Amidan. Nach einer Empfehlung von Nathan Milstein zog Yair nach Br\u00fcssel, um bei Prof. Andre Gertler am K\u00f6niglichen Konservatorium und der Chapelle-Musicale Reine-Elizabeth zu studieren, wo er sowohl im Instrumental- als auch im Kammermusikbereich mit h\u00f6chster Auszeichnung abschloss. Yair wurde schnell zu einem bekannten Solisten und Kammermusiker. Sein umfangreiches Repertoire reicht von Barock bis Moderne und umfasst auch Urauff\u00fchrungen von Werken, von denen einige speziell f\u00fcr ihn geschrieben oder ihm gewidmet wurden. Yair war einer der Gr\u00fcnder und erster Geiger des Sol-La-Re-Streichquartetts, das unter anderem wichtige Werke israelischer Komponisten einspielte. Er war Mitglied der \u201eIsraeli Baroque Players\u201c, die ausgiebig um die Welt tourten und unter anderem an den renommierten Salzburger Festspielen teilnahmen. Zu weiteren Ensembles und Gruppen geh\u00f6ren das \u201eTel-Aviv Piano Quartet\u201c, das in den USA ans\u00e4ssige \u201eNew Art Trio\u201c, das Modus Trio, das Modus Ensemble sowie zahlreiche internationale Projekte und Festivals. Er genie\u00dft die Zusammenarbeit mit seinem Sohn Eyal im Duo-Violinen-Repertoire. Yair hat den Gro\u00dfteil des Sonatenrepertoires aufgef\u00fchrt und dabei mit herausragenden musikalischen Partnern wie Nadia Reisenberg, Pnina Salzman, Shoshana Rudiakov, Arie Vardi, Victor Derevianko, Frank Wibout, Victor Yampolski und Pascal Sigrist zusammengearbeitet. Neben seinen kammermusikalischen Aktivit\u00e4ten verfolgt Yair eine Karriere als Solist und hat mehr als 30 Violinkonzerte in seinem Repertoire. Als einer der bedeutendsten Lehrer der Welt haben viele von Yairs Sch\u00fclern eine erfolgreiche Solo- und Kammermusikkarriere erreicht, Preise bei Wettbewerben gewonnen und wichtige Lehr- und Auff\u00fchrungspositionen inne.           <\/span><\/p><p><span style=\"color: #ffffff;\"><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\"> <\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7db00f #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b7db00f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38f61c8 e-con-full gradient-background15 e-flex elementor-invisible e-con e-child\" data-id=\"38f61c8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dac32bc elementor-widget elementor-widget-menu-anchor\" data-id=\"dac32bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Gahl\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49d8535 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"49d8535\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Annelie Gahl, Violine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83d2d3e animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"83d2d3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"wp-image-23241 alignleft\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/AnnelieGahl-0035.jpg?resize=300%2C451&#038;ssl=1\" alt=\"\" width=\"300\" height=\"451\"><\/p><p class=\"p1\"><span style=\"color: #ffffff;\">Annelie Gahl studierte bei Paul Roczek, Harald Herzl und Ernst Kovacic an der Universit\u00e4t Mozarteum und an der Wiener Musikhochschule, weiters postgraduate bei Herman Krebbers in Amsterdam und Shmuel Ashkenasi an der Northern Illinois University. K\u00fcnstlerisch pr\u00e4gend wurden f\u00fcr sie zudem ihre Zusammenarbeit mit Sandor Vegh und Nikolaus Harnoncourt, in deren Orchester Camerata Salzburg und Concentus musicus Annelie Gahl seit vielen Jahren zum Stammspielerkreis z\u00e4hlt. Zudem ma\u00dfgeblich f\u00fcr ihre vielseitige und lebendige T\u00e4tigkeit ist die Hinwendung zur Neuen Musik. Dies sowohl als regelm\u00e4ssiger Gast im Klangforum Wien, als auch als Solistin. Ihre kreativen Programme, vielfach in Zusammenhang mit Literatur, Tanz und bildender Kunst brachten sie auf Festivals, wie Wien Modern, Salzburger Festspiele, Salzburg Biennale, Osterfestival Hall, Styriarte, Ulrichsberger Kaleidophon, Festival Imago Dei, in die Philharmonie Luxemburg, uva. Internationale Anerkennung erlangte sie durch ihre Solo Einspielungen, erschienen bei Extraplatte, collegno und Kairos, auf denen sie Alte und Neue Musik verkn\u00fcpft. So wurde ihre Cage Einspielung gemeinsam mit dem Komponisten Klaus Lang, umgehend mit dem Pasticcio Preis des ORF ausgezeichnet, vom deutschen Rondo Magazin als die \u201ewohl sch\u00f6nste seit vielen Jahren\u201c bezeichnet, das Strad Magazin schw\u00e4rmte von einem \u201eauspicious and exciting Solo Debut\u201c, und die Salzburger Nachrichten attestierten ihr \u201efamos fokussierte Geigenkunst\u201c. Annelie Gahl ist Tr\u00e4gerin des Anton Bruckner Preises, sowie des Paula Boleszny Preises. Als Solistin interpretierte sie mit der Camerata Salzburg, der Salzburger Kammerphilharmonie, sowie der Sinfonietta Danubia Werke von Ludvig van Beethoven, Antonio Vivaldi und Steve Reich. Als Kammermusikerin musizierte sie unter anderem mit Benjamin Schmid, Ivry Gitlis, Lukas und Veronika Hagen, dem Hyperion Ensemble, sowie Mitgliedern des Klangforum Wien und der Camerata Salzburg. Einen wichtigen Schwerpunkt bildet f\u00fcr sie seit 2000 das Unterrichten an der Universit\u00e4t Mozarteum, wo sie seit ihrer Habilitierung im Jahr 2017 eine Violinklasse leitet. Meisterkurse und Ensemblecoaching in \u00d6sterreich, Israel, Deutschland, Moskau und China erg\u00e4nzen diese T\u00e4tigkeit.            <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f13c4b #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1f13c4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94d1182 e-con-full gradient-background4 e-flex elementor-invisible e-con e-child\" data-id=\"94d1182\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b51bba elementor-widget elementor-widget-menu-anchor\" data-id=\"1b51bba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Winokurow\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb64d5c animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cb64d5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wladislaw Winokurow, Violine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6835466 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6835466\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignleft wp-image-22083 size-large\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2025\/01\/DSC04253.jpg?resize=800%2C533&#038;ssl=1\" alt=\"\" width=\"800\" height=\"533\"><\/span><\/p><p class=\"p1\"><span style=\"color: #ffffff;\">Wladislaw Winokurow wurde in Kiew in einer bedeutende Musikerfamilie geboren und tauchte schon in jungen Jahren in die Welt der Musik ein. Seine k\u00fcnstlerische Laufbahn begann im Alter von f\u00fcnf Jahren unter der Anleitung seines Vaters und f\u00fchrte ihn schnell an die renommierte Spezialmusikschule f\u00fcr begabte Kinder. Dort erhielt er, eingebettet in die strenge Tradition der Kiewer Violinschule, eine intensive Ausbildung bei Alexander Panov, Avanes Buludian und Isaak Kushnir. Bereits im Alter von zehn Jahren stellte Winokurow sein fr\u00fchreifes Talent bei Solodeb\u00fcts mit dem Kiewer Kammerorchester unter Beweis \u2013 ein Vorspiel f\u00fcr seinen Umzug nach \u00d6sterreich im Jahr 1992, der seine k\u00fcnstlerische Identit\u00e4t entscheidend pr\u00e4gen sollte. In Wien, der Hauptstadt der klassischen Musik, gelang es Winokurow, die technische Virtuosit\u00e4t seiner \u00f6stlichen Wurzeln mit der stilistischen Eleganz der Wiener Tradition zu verbinden. Er verfeinerte sein Handwerk an der Wiener Musikhochschule und der Universit\u00e4t f\u00fcr Musik und darstellende Kunst Wien unter der Anleitung renommierter Mentoren wie Eugenia Polatschek, Gernot Winischhofer und dem legend\u00e4ren Boris Kuschnir. Seine musikalische Pers\u00f6nlichkeit wurde durch Meisterkurse bei Violinen-Gr\u00f6\u00dfen wie Abraham Stern, Zakhar Bron und Viktor Tretyakov weiter gepr\u00e4gt, wodurch er tiefe Einblicke in das gro\u00dfe Violinenrepertoire gewann. Als Gr\u00fcnder und Primarius des Gli\u00e8re String Quartetts hat sich Winokurow eine bedeutende internationale Pr\u00e4senz in der Welt der Kammermusik erarbeitet. Nach dem triumphalen 1. Preis beim 8. Internationalen Beethoven-Wettbewerb 2012 trat das Ensemble auf renommierten B\u00fchnen weltweit auf, vom Goldenen Saal des Wiener Musikvereins bis hin zu ber\u00fchmten Festivals wie dem Nikodemowicz-Festival, dem \u201eOpus Magnum\u201d-Festival und dem Harmonie Starego Miasta in Polen. W\u00e4hrend das Repertoire des Quartetts von der fr\u00fchen Wiener Klassik bis zur zeitgen\u00f6ssischen Avantgarde reicht, hat Winokurow einen wesentlichen Teil seiner k\u00fcnstlerischen Mission der Wiederentdeckung und Interpretation des slawischen Repertoires gewidmet. Er ist besonders bekannt f\u00fcr sein Engagement f\u00fcr ukrainische und sowjetische Komponisten wie Borodin, Myaskovsky, Schostakowitsch und den Namensgeber des Ensembles, Reinhold Gli\u00e8re. Seit 2020 sind aus einer fruchtbaren Zusammenarbeit mit dem Label DUX hochgelobte Aufnahmeserien hervorgegangen, darunter die Streichquartette von R. Gli\u00e8re neben Meisterwerken von Bruckner, Mendelssohn und Ravel, die f\u00fcr ihre Ausdruckskraft und klangliche Raffinesse gelobt wurden. \u00dcber die Konzertb\u00fchne hinaus ist Wladislaw Winokurow ein angesehener P\u00e4dagoge, der sich der F\u00f6rderung der n\u00e4chsten Generation von Violinisten verschrieben hat. Seit 2018 hat Wladislaw Winokurow eine Lehrstelle an der Universit\u00e4t f\u00fcr Musik und darstellende Kunst Graz (KUG) inne. Sein p\u00e4dagogischer Ansatz, der sich auf die Entwicklung einer ausgepr\u00e4gten k\u00fcnstlerischen Pers\u00f6nlichkeit konzentriert, zeigt sich in den au\u00dfergew\u00f6hnlichen Erfolgen seiner Sch\u00fcler, die \u00fcber 60 Siege bei nationalen und internationalen Wettbewerben vorweisen k\u00f6nnen. Als gefragter Mentor leitet er regelm\u00e4\u00dfig Meisterkurse in ganz Europa und gibt sein Fachwissen an der Kulturwelten Sommerakademie (Wien), dem European Music Institute Vienna, den Austrian Master Classes (Salzburg) und der Wieniawski Society in Lublin weiter. Dar\u00fcber hinaus ist er ein angesehenes Jurymitglied bei renommierten Wettbewerben wie dem Bundeswettbewerb Prima la Musica in \u00d6sterreich, dem Vasa Prihoda und den Kocian-Violinwettbewerben in der Tschechischen Republik.                <\/span><\/p><p><span style=\"color: #ffffff;\"> <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c531141 #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c531141\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d80c277 e-con-full gradient-background16 e-flex elementor-invisible e-con e-child\" data-id=\"d80c277\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82e34a4 elementor-widget elementor-widget-menu-anchor\" data-id=\"82e34a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Brand\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-188f9ae animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"188f9ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Regina Brandst\u00e4tter, Violine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a4135f animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3a4135f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-wp-editing=\"1\"><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignright wp-image-23946\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2026\/01\/Brandstaetter_Regina_1.jpg.webp?resize=367%2C550&#038;ssl=1\" alt=\"\" width=\"367\" height=\"550\" srcset=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2026\/01\/Brandstaetter_Regina_1.jpg.webp?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2026\/01\/Brandstaetter_Regina_1.jpg.webp?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2026\/01\/Brandstaetter_Regina_1.jpg.webp?resize=768%2C1152&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2026\/01\/Brandstaetter_Regina_1.jpg.webp?resize=1024%2C1536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2026\/01\/Brandstaetter_Regina_1.jpg.webp?resize=600%2C900&amp;ssl=1 600w\" sizes=\"(max-width: 367px) 100vw, 367px\" \/><span style=\"color: #ffffff;\">Regina Brandst\u00e4tter stammt aus Graz und hat an der damaligen Musikhochschule Wien Konzertfach Violine studiert. Sie ist als Solistin und Kammermusikerin in zahlreichen Konzerten im in und Ausland zu h\u00f6ren gewesen. Auftritte als Solistin mit dem Tonk\u00fcnstler Orchester, mit dem Bruckner Orchester Linz, dem Orchestre National des Pays de la Loire waren besonders sch\u00f6ne Stationen im k\u00fcnstlerischen Leben. Die CD Solo for two Violins, gemeinsam mit Raimund Lissy, Tobias Lea und Cordelia H\u00f6fer-Teutsch wurde 2009 mit dem \u00d61- ORF Pasticcio Preis ausgezeichnet. Der Schwerpunkt ihrer T\u00e4tigkeit als Musikerin lag aber in der Arbeit mit jungen, hochbegabten Talenten. Seit 1996 lehrt sie an der Kunstuniversit\u00e4t Graz\/ Institut Obersch\u00fctzen und leitet eine Ausbildungsklasse f\u00fcr den Nachwuchs. 2012 wurde ihr die Venia Docendi nach ihrer Habilitation verliehen, seit dem lehrt sie als a.o Universit\u00e4tsprofessorin der Kunstuniversit\u00e4t. Viele ihrer Studierenden sind mehrfache internationale Preistr\u00e4ger, spielen bereits in renommierten Orchestern wie dem Bruckner Orchester Linz, im Orchester der Wiener Philharmoniker oder sind als internationale Solisten erfolgreich t\u00e4tig.       <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7da23ee #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7da23ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eea3995 e-con-full gradient-background8 e-flex elementor-invisible e-con e-child\" data-id=\"eea3995\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a46c23 elementor-widget elementor-widget-menu-anchor\" data-id=\"6a46c23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Kalisch\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9e5651 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c9e5651\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Andrei Kalisch, Violine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f86497b animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"f86497b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"wp-image-19136 alignleft\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Andrei-10-scaled-2.jpeg?resize=300%2C406&#038;ssl=1\" alt=\"\" width=\"300\" height=\"406\" srcset=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Andrei-10-scaled-2.jpeg?w=1420&amp;ssl=1 1420w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Andrei-10-scaled-2.jpeg?resize=600%2C811&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Andrei-10-scaled-2.jpeg?resize=370%2C500&amp;ssl=1 370w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Andrei-10-scaled-2.jpeg?resize=757%2C1024&amp;ssl=1 757w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Andrei-10-scaled-2.jpeg?resize=768%2C1038&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Andrei-10-scaled-2.jpeg?resize=1136%2C1536&amp;ssl=1 1136w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Andrei-10-scaled-2.jpeg?resize=1200%2C1623&amp;ssl=1 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Andrei Kalisch ist Leiter der Violinklasse an der Margareten Musikschule in Wien. Seit 2005 ist er intensiv in der Lehre t\u00e4tig. Seine Sch\u00fcler haben sich als Preistr\u00e4ger renommierter internationaler Wettbewerbe wie dem Kocian-Violinwettbewerb (Tschechische Republik), dem Internationalen Grumiaux-Violinwettbewerb (Belgien) und dem Leonid-Kogan-Violinwettbewerb (Belgien) einen Namen gemacht.   <\/span><span style=\"color: #ffffff;\">Er ist au\u00dferdem Direktor der Jehuda Halevi Musikschule in Wien. Gewinner von Solo- und Kammermusikwettbewerben. Soloauftritte mit dem Alma-Ata Philharmonic Orchestra, Konzerte als Solist und Kammermusiker in vielen europ\u00e4ischen L\u00e4ndern sowie in Japan, China, S\u00fcdkorea, Brasilien und Kolumbien. CD- und Fernsehaufnahmen. Andrei Kalisch wurde in Alma-Ata, Kasachstan, geboren. Zu Beginn seiner musikalischen Laufbahn nahm er Unterricht bei seinem Gro\u00dfvater. Er war Sch\u00fcler von J. Lesman (Assistent von L. Auer) und E. Antopolski (Sch\u00fcler von J. Thibaud). Sp\u00e4ter studierte er an der Musikhochschule und am Konservatorium in Alma-Ata bei Professor S. Abdusadikova (Sch\u00fcler von M. Garlitsky und A. Markov) und Professor D. Kaseinov (Sch\u00fcler von I. Bezrodny) sowie am Bruckner-Konservatorium in Linz bei Professor Arkadij Winokurow.       <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f4a74a #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4f4a74a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c2957f1 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"c2957f1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d895f0 elementor-widget elementor-widget-menu-anchor\" data-id=\"6d895f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Tichonow\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f58c420 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f58c420\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Stanislaw Tichonow, Klavier<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afe5dd3 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"afe5dd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignleft size-medium wp-image-20411\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/IMG_0079.jpg?resize=500%2C282&#038;ssl=1\" alt=\"\" width=\"500\" height=\"282\" srcset=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/IMG_0079.jpg?w=936&amp;ssl=1 936w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/IMG_0079.jpg?resize=500%2C282&amp;ssl=1 500w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/IMG_0079.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/IMG_0079.jpg?resize=600%2C338&amp;ssl=1 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>Prof. Dr. Tichonow erhielt seine professionelle Ausbildung am Staatlichen Konservatorium \u201eM. I. Glinka\u201c in Nowosibirsk in Russland (M.A. in Klavierperformance bei L. Slonim) und am Staatlichen Konservatorium \u201eP. l .Tschaikowsky\u201c in Moskau (D.M.A. in Klavierperformance bei R. Kehrer und PhD. in Musikwissenschaft bei M. Smirnov).<\/span><br>S. Tichonow ist ein Vertreter der Tradition von Theodor Leschetizky. Zu seinen wissenschaftlichen Arbeiten z\u00e4hlen mehr als 40 Fachartikel, die in russischen, amerikanischen und \u00f6sterreichischen musikwissenschaftlichen Zeitschriften ver\u00f6ffentlicht wurden, sowie das Buch \u201eLeschetizky und sein Wiener Kreis\u201c (Wien, 2001). Neben seiner Karriere als Pianist und Musikwissenschaftler ist Prof. Tichonow derzeit Professor an der Klavierfakult\u00e4t der Joseph Haydn Privathochschule in Eisenstadt, \u00d6sterreich; zuvor war er am Tschaikowsky-Konservatorium in Moskau und am Konservatorium in Wien (heute MUK) t\u00e4tig. Er trat intensiv als Solist und Begleiter auf, spielte Kammermusik als Gr\u00fcnder seines eigenen Leschetizky-Trios in Wien, h\u00e4lt Vortr\u00e4ge und gibt Meisterkurse in ganz Europa, den USA (Yale Summer School of Music) und im Fernen Osten. Seine Sch\u00fcler haben mehr als 100 Preise bei internationalen Wettbewerben in Deutschland, Italien, Schweden, Frankreich, Georgien, Finnland, Portugal, den USA, Bulgarien, der T\u00fcrkei, dem Iran, Spanien, der Tschechischen Republik, Russland und \u00d6sterreich gewonnen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df38a5e #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"df38a5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ebbf77d e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"ebbf77d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87ef4a5 elementor-widget elementor-widget-menu-anchor\" data-id=\"87ef4a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Gulda\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e75bb89 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e75bb89\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Paul Gulda, Klavier<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3764f07 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3764f07\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"size-full wp-image-19131 alignnone\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Juni-2014.-von-Josef-LEITNER-1-scaled-2.jpg?resize=800%2C534&#038;ssl=1\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Juni-2014.-von-Josef-LEITNER-1-scaled-2.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Juni-2014.-von-Josef-LEITNER-1-scaled-2.jpg?resize=600%2C400&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Juni-2014.-von-Josef-LEITNER-1-scaled-2.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/02\/Juni-2014.-von-Josef-LEITNER-1-scaled-2.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\u200b<span style=\"color: #ffffff;\">Geboren 1961 in Wien, \u00d6sterreich. Vater Friedrich Gulda, Pianist\/Komponist. Mutter Paola Loew, Schauspielerin. Erste Auftritte in der Kammermusik 1979, seit 1982 internationale Konzertt\u00e4tigkeit (Hagen Quartett, Heinrich Schiff), als Duo-Pianist mit Roland Batik. Als Solist mit dem Wiener Philharmonischen Orchester\/Mehta, den Wiener Symphonikern, dem Gewandhausorchester Leipzig\/Masur, den Moskauer Philharmonikern\/Fedossejew. Umfangreiche Erfahrung als Komponist, Dirigent, Improvisator; Zusammenarbeit mit (Folk-)Musikern unterschiedlicher Herkunft, mit Schauspielern, Autoren und Malern. Er interessiert sich leidenschaftlich f\u00fcr Klang und Stil und spielt au\u00dferdem Hammerklavier, Cembalo, Clavichord und Orgel. Seit 2018 bilden Auff\u00fchrungen von Bachs WTC I das R\u00fcckgrat seiner Arbeit. Etwa 30 CDs in verschiedenen Bereichen. Als Mentor und Lehrer sehr gefragt, zeichnen sich seine Sch\u00fcler dadurch aus, dass sie ihren ganz eigenen Weg finden. Derzeit hat er eine Lehrstelle an der Friedrich Gulda Musikschule Wien inne. Seine Kompositionen konzentrieren sich haupts\u00e4chlich auf die menschliche Stimme und den dramatischen Kontext. Politischer Aktivismus. (REFUGIUS Rechnitz). Verschiedene Essays und Ver\u00f6ffentlichungen in Programmen, Zeitungen, Medien.              <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e01767 #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7e01767\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38ddd68 e-con-full gradient-background9 e-flex elementor-invisible e-con e-child\" data-id=\"38ddd68\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bd4a23 elementor-widget elementor-widget-menu-anchor\" data-id=\"4bd4a23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Kharin\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac2ee64 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ac2ee64\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vladimir Kharin, Klavier<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ed0e37 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2ed0e37\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"size-medium wp-image-21161 alignleft\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/KahrinV.png?resize=500%2C333&#038;ssl=1\" alt=\"\" width=\"500\" height=\"333\" srcset=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/KahrinV.png?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/KahrinV.png?resize=500%2C333&amp;ssl=1 500w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/KahrinV.png?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/KahrinV.png?resize=600%2C400&amp;ssl=1 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>Vladimir Kharin ist bekannt als erfolgreicher Pianist und Lehrer. Seine musikalische Ausbildung begann an der Zentralen Musikschule f\u00fcr begabte Kinder in Moskau. Vladimir Kharin studierte am Moskauer Tschaikowsky-Konservatorium bei Evgeny Malinin und Lev Naumov, beides Vertreter der ber\u00fchmten Neuhaus-Klavierschule. 1998 erhielt der Pianist ein Stipendium des Deutschen Akademischen Austauschdienstes (DAAD), das ihm erm\u00f6glichte, sein Studium bei Michael Roll und Boris Bloch an der Folkwang Universit\u00e4t der K\u00fcnste in Essen fortzusetzen. Vladimir Kharin bestand sowohl seine k\u00fcnstlerische Abschlusspr\u00fcfung als auch seine Konzertpr\u00fcfung mit Auszeichnung. Als Preistr\u00e4ger internationaler Wettbewerbe wurde Kharin zu zahlreichen Solo- und Kammermusikabenden sowie Konzerten mit Orchester eingeladen. Er hat mehrere Konzerte beim Klavierfestival Ruhr gegeben. Vladimir Kharin hat mehrere CDs aufgenommen, unter anderem in Zusammenarbeit mit Jonathan Darlington. Der Pianist widmet sich mit besonderer Leidenschaft der F\u00f6rderung junger Talente.       <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6699978 #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6699978\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c8ccb9 e-con-full gradient-background6 e-flex elementor-invisible e-con e-child\" data-id=\"0c8ccb9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1e3684 elementor-widget elementor-widget-menu-anchor\" data-id=\"d1e3684\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Fliedl\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5ddf4e animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a5ddf4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Jeremias Fliedl, Violoncello<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5668ec4 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"5668ec4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p2\"><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"alignleft wp-image-23265\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/Bildschirmfoto-2025-12-25-um-19.08.01.png?resize=582%2C697&#038;ssl=1\" alt=\"\" width=\"582\" height=\"697\" srcset=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/Bildschirmfoto-2025-12-25-um-19.08.01.png?w=1598&amp;ssl=1 1598w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/Bildschirmfoto-2025-12-25-um-19.08.01.png?resize=855%2C1024&amp;ssl=1 855w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/Bildschirmfoto-2025-12-25-um-19.08.01.png?resize=768%2C920&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/Bildschirmfoto-2025-12-25-um-19.08.01.png?resize=1282%2C1536&amp;ssl=1 1282w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/Bildschirmfoto-2025-12-25-um-19.08.01.png?resize=600%2C719&amp;ssl=1 600w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/><em>&#8222;Im Schumann Konzert zeigte Fliedl ein echtes Gesp\u00fcr f\u00fcr die \u2018Storyline\u2019 und scheute sich nicht, \u00fcber einen sch\u00f6nen Klang hinauszugehen, wenn die Musik es verlangte, w\u00e4hrend er sich zwischen ergreifenden Pianissimi und Momenten leidenschaftlichen Wahnsinns bewegte.&#8220;<\/em><\/p><p class=\"p2\">&#8211; Pauline Harding, The Strad (25.07.2022)<\/p><p class=\"p2\"><em>\u201eEr ist jemand, der es versteht, das Cello singen zu lassen, der die melodischen B\u00f6gen der Musik voll auskostet, ihnen Zeit zur Entfaltung gibt.\u201c<\/em><\/p><p class=\"p2\">&#8211; Holger Sambale, Klassik Heute (11.03.2024).<\/p><p class=\"p2\">Jeremias Fliedl ist einer der f\u00fchrenden \u00f6sterreichischen Cellisten. Er gastierte bei renommierten Festivals und in bedeutenden Spielst\u00e4tten, darunter die Salzburger Festspiele, die Mozartwoche Salzburg, die Schubertiade Hohenems, die Festspiele Mecklenburg-Vorpommern, der Carinthische Sommer, das S\u00fcdtirol Festival Merano, CLASSIX Kempten, die Musiktage Mondsee, das Vevey Spring Classic Festival, das Internationale Kammermusikfestival Utrecht, das Grachtenfestival Amsterdam, das Viotti Festival, das Lake District Summer Music Festival, die Salzkammergut Festwochen Gmunden, das Festival Sankt Gallen, der Wiener Musikverein, das Wiener Konzerthaus, das Palais des Beaux-Arts Br\u00fcssel, das Konzerthaus Dortmund und die Laeiszhalle Hamburg. Als Kammermusiker trat er u. a. mit Petrit \u00c7eku, Veronika Eberle, Karen Gomyo, Ariane Haering, Ziyu He, Maximilian Kromer, Matthew Lipman, Gerhard Marschner, Callum McLachlan, Nikola Meeuwsen, Nils M\u00f6nkemeyer, Daniel M\u00fcller-Schott, Benedict Mitterbauer, Julian Rachlin, Timothy Ridout, Linus Roth, Benjamin Schmid, dem Simply Quartet, Emmanuel Tjeknavorian, Kiron Atom Tellian, Dimitry Udovichenko und Dominik Wagner auf. Als Solist konzertierte er mit Orchestern wie den Br\u00fcsseler Philharmonikern, dem Orchestra Sinfonica di Milano, den Bremer Philharmonikern, dem Thessaloniki State Symphony Orchestra, dem Danish Chamber Orchestra, dem K\u00f6niglich-Wallonischen Kammerorchester, dem W\u00fcrttembergischen Kammerorchester Heilbronn, dem M\u00fcnchener Kammerorchester, den Salzburger Orchester Solisten, den Zagreber Solisten, dem Zagreb Chamber Orchestra, der Beethoven Philharmonie, dem Matrix Orchestra, dem Changsha Symphony Orchestra, dem K\u00e4rntner Sinfonieorchester, der Academia Ars Musicae, der \u00d6sterreichisch-Koreanischen Philharmonie, der Euro Symphony SFK, dem Sinfonieorchester der Philharmonie Olsztyn und dem Kaunas City Symphony Orchestra. Er arbeitete mit Dirigenten wie St\u00e9phane Den\u00e8ve, \u00c1d\u00e1m Fischer, Martin Haselb\u00f6ck, Thomas Sanderling, Case Scaglione und wird kommende Saison erstmals mit Joji Hattori, Thomas Guggeis und Przemys\u0142aw Neumann auftreten. Jeremias Fliedl wird mit dem Orchestra della Toscana, mit dem Wiener KammerOrchester, mit dem Orchestre National de Lyon wie auch mit dem Sinfonieorchester der Philharmonie Szczecin Orchestra deb\u00fctieren. 2024 erschien sein Deb\u00fct-Album \u201eTRANSFORMATION\u201c, das bei der Fachwelt gro\u00dfen Anklang fand: &#8222;ein pr\u00e4chtiges Fest von Cello-Timbres&#8220; (BBC Music Magazine), \u201efulminant\u201c (Die Presse), \u201etechnisch brillant und mit erstaunlicher musikalischer Reife\u201c (Concerti), \u201cmitrei\u00dfend\u201d (Salzburger Nachrichten), \u201ebeseelte Expressivit\u00e4t, herrliches Legato\u201c (Klassik Heute). Das Album wurde mit dem W\u00fcrttembergischen Kammerorchester Heilbronn unter Emmanuel Tjeknavorian aufgenommen und erschien beim Label Berlin Classics. 1999 in Klagenfurt geboren, wurde Jeremias Fliedl nach der Grundausbildung bei Igor Mitrovic in seiner musikalischen Entwicklung wesentlich von Heinrich Schiff als dessen letzter Student an der Universit\u00e4t f\u00fcr Musik und darstellende Kunst Wien gepr\u00e4gt. Er absolvierte sein Bachelorstudium bei Clemens Hagen an der Universit\u00e4t Mozarteum Salzburg und schloss sein Masterstudium bei Julian Steckel an der Hochschule f\u00fcr Musik und Theater M\u00fcnchen ab. Wichtige k\u00fcnstlerische Impulse erhielt er von Daniel M\u00fcller-Schott und Michael Sanderling. Er ist Preistr\u00e4ger des Liezen Wettbewerbs, des Svir\u00e9l Wettbewerbs, des Antonio Janigro Wettbewerbs und zudem als erster \u00f6sterreichischer Cellist Preistr\u00e4ger des Queen Elisabeth Wettbewerbs. Jeremias Fliedl spielt das &#8222;ex Gendron, Lord Speyer&#8220;, ein Violoncello von Antonio Stradivari aus dem Jahr 1693, das ihm privat zur Verf\u00fcgung gestellt wird.            <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27b9b23 #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"27b9b23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-abfec54 e-con-full gradient-background7 e-flex elementor-invisible e-con e-child\" data-id=\"abfec54\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-237f7b0 elementor-widget elementor-widget-menu-anchor\" data-id=\"237f7b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Zelenin\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afb23bf animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"afb23bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Konstantin Zelenin, Violoncello<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18586c3 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"18586c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"wp-image-23260 alignleft\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2025\/12\/DSC8251.jpg?resize=545%2C817&#038;ssl=1\" alt=\"\" width=\"545\" height=\"817\"><\/span><\/p><p class=\"p1\"><span style=\"color: #ffffff;\">Konstantin Zelenin wurde 1983 in Minsk geboren und begann im Alter von sechs Jahren mit dem Violoncellounterricht. Er schloss sein Studium \u201emit Auszeichnung\u201c am Moskauer Tschaikowsky-Konservatorium bei Prof. Natalia Schakhovskaya sowie an der Musikakademie in Minsk bei Prof. Vladimir Perlin ab, wo ihm der akademische Grad \u201eMagister Artium\u201c verliehen wurde. Ab 2009 setzte er sein Studium an der Universit\u00e4t f\u00fcr Musik und darstellende Kunst in Wien in der Klasse von Univ.-Prof. Mag. Stefan Kropfitsch fort. 2015 schloss er sein Masterstudium \u201emit Auszeichnung\u201c bei Prof. Natalia Gutman an der MUK Privatuniversit\u00e4t Wien ab. Zelenin ist dreifacher Stipendiat der \u201eSpecial Foundation by the President of the Republic of Belarus for Talented Youth\u201c und Gewinner des \u201eGrand Prix\u201c beim Wettbewerb \u201eArts of XXI Century\u201c in Kiew. Er hat bei zahlreichen internationalen Violoncello-Wettbewerben verschiedene Preise gewonnen, darunter der \u201eGrodno Streicher Wettbewerb\u201c (Wei\u00dfrussland, 2000), der \u201eE. Koka Wettbewerb\u201c (Kishiney, Moldawien, 2003), der \u201eM. Elsky Wettbewerb\u201c (Minsk, Wei\u00dfrussland, 2003 und 2008), der \u201eK. Davidov Wettbewerb\u201c (Kuldiga, Lettland, 2004), der \u201eLiezen Cello Wettbewerb\u201c (Liezen, \u00d6sterreich, 2010), der \u201eBeethoven Streichquartett Wettbewerb\u201c (St. P\u00f6lten, \u00d6sterreich) und die \u201eEugen Isaye International Competition\u201c (L\u00fcttich, Belgien). Zelenin ist Gr\u00fcndungsmitglied des Auner Quartetts, das seinen eigenen kammermusikalischen Zyklus im Alten Wiener Rathaus ins Leben rief. Unterst\u00fctzt wird das Quartett unter anderem von \u201eRadio Klassik\u201c, \u201eDie Presse\u201c, der \u201eBank Austria\u201c, \u201eRadio Stephansdom\u201c und Musikhaus Laimer. Das Auner Quartett trat in renommierten Konzerth\u00e4usern wie dem Wiener Konzerthaus und dem Wiener Musikverein auf und veranstaltet seit 2015 einen eigenen Kammermusik-Zyklus in Wien. Das Quartett konzertiert sowohl in \u00d6sterreich als auch international. Als Solist und Kammermusiker konzertierte Konstantin Zelenin in Europa, Amerika und Asien. Er spielte mit renommierten Orchestern wie dem Wei\u00dfrussischen Nationalsinfonieorchester, dem Nationalkammerorchester, dem Wei\u00dfrussischen Rundfunksinfonieorchester, dem Symphonieorchester Brest, dem Symphonieorchester Gomel und dem Riga Philharmonic Symphony Orchestra. Seine Konzertt\u00e4tigkeit ist durch zahlreiche Fernseh- und Rundfunkaufnahmen in Wei\u00dfrussland und \u00d6sterreich dokumentiert. Zelenin hat mehrere erfolgreiche CD-Aufnahmen vorzuweisen. Besonders hervorzuheben ist seine Einspielung des Mozart-Klarinettenquintetts, das von \u201eRadio Klassik\u201c als \u201eCD des Monats\u201c ausgezeichnet wurde. Zudem wurde eine Produktion von Werken der Komponistin Johanna Doderer von \u00d61 als \u201eCD der Woche\u201c geehrt. Eine weitere Aufnahme mit Werken \u00f6sterreichischer Komponisten des 20. Jahrhunderts wurde 2022 von Radio \u00d61 als \u201eCD des Jahres\u201c ausgezeichnet. Vor seiner \u00dcbersiedlung nach Wien in den Jahren 2008 und 2009 unterrichtete Zelenin an der Wei\u00dfrussischen Akademie f\u00fcr Musik, am Musikalischen Gymnasium sowie an der staatlichen Musikschule in Minsk, wo er als Dozent f\u00fcr Violoncello und Kammermusik t\u00e4tig war und als Assistent von Prof. Perlin arbeitete. Von 2016 bis 2021 lehrte er an verschiedenen privaten Konservatorien in Wien.                         Seit 2021 ist Konstantin Zelenin als Lehrer an der Friedrich Gulda School of Music (Jam Music Lab Privatuniversit\u00e4t) in Wien t\u00e4tig.<\/span><\/p><p><span style=\"color: #ffffff;\"> <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf7ba85 #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bf7ba85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ad77e19 e-con-full gradient-background30 e-flex elementor-invisible e-con e-child\" data-id=\"ad77e19\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c043771 elementor-widget elementor-widget-menu-anchor\" data-id=\"c043771\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Kitanovic\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e4be16 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1e4be16\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ivan Kitanovi\u0107, Kontrabass<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f608d3 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2f608d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"wp-image-20967 alignright\" src=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/Bild-26.01.24-um-13.17-2.jpg?resize=300%2C345&#038;ssl=1\" alt=\"\" width=\"300\" height=\"345\" srcset=\"https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/Bild-26.01.24-um-13.17-2.jpg?w=1670&amp;ssl=1 1670w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/Bild-26.01.24-um-13.17-2.jpg?resize=435%2C500&amp;ssl=1 435w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/Bild-26.01.24-um-13.17-2.jpg?resize=891%2C1024&amp;ssl=1 891w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/Bild-26.01.24-um-13.17-2.jpg?resize=768%2C883&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/Bild-26.01.24-um-13.17-2.jpg?resize=1336%2C1536&amp;ssl=1 1336w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/Bild-26.01.24-um-13.17-2.jpg?resize=600%2C690&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.kulturwelten.at\/wp-content\/uploads\/2024\/12\/Bild-26.01.24-um-13.17-2.jpg?w=1600&amp;ssl=1 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><br>Ivan Kitanovi\u0107 wurde 1976 in Kru\u0161evac (heute Serbien) geboren. Seine gro\u00dfe Liebe zur Musik zeigte sich schon fr\u00fch: Er brachte sich selbst das Gitarre- und Akkordeonspielen bei, bevor sein gro\u00dfes musikalisches Talent entdeckt wurde und er in das renommierte Musikinternat in \u0106uprija aufgenommen wurde. Dort zeigte sich bald seine herausragende Begabung f\u00fcr den Kontrabass, und er erzielte in k\u00fcrzester Zeit gro\u00dfe Erfolge auf diesem Instrument: Er gewann den ersten Preis bei f\u00fcnf nationalen und internationalen Wettbewerben, gefolgt von zahlreichen Soloauftritten mit Orchester, Live-\u00dcbertragungen und Portr\u00e4ts in Fernsehen und Radio. Unmittelbar nach seinem Abschluss an der Musikinternatsschule \u0106uprija mit der bisher h\u00f6chsten Auszeichnung wurde er Solobassist bei den Belgrade Strings und studierte gleichzeitig an der Musikakademie Belgrad. Ab 2000 setzte er sein Studium bei Josef Niederhammer an der Universit\u00e4t f\u00fcr Musik in Wien fort, wo er bald an seine bisherigen Erfolge ankn\u00fcpfen konnte: So wurde er beispielsweise als musikalischer Vertreter Europas f\u00fcr den hochgelobten Pausenfilm des weltweit ausgestrahlten Neujahrskonzerts 2003 ausgew\u00e4hlt und war Mitglied mehrerer Orchester (darunter das B\u00fchnenorchester der Wiener Staatsoper). Seit 2003 ist er 1. Solokontrabassist der Wiener Symphoniker. Ivan Kitanovi\u0107 widmet sich der Erweiterung des Kontrabass-Repertoires und nimmt auch bedeutende Werke der Celloliteratur in seine Konzerte auf. Dadurch gelingt es ihm, den Kontrabass als musikalisch vollwertiges, klanglich beeindruckendes Soloinstrument zu positionieren. Seine Liebe zur Kammermusik lebt er mit dem weltweit auftretenden Trio \u201eImpossibile\u201c aus und wird regelm\u00e4\u00dfig von renommierten Ensembles (wie dem Hugo Wolf Quartett, dem EOS Quartett, dem Ensemble \u201edie reihe\u201c) eingeladen.       <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef80f9c #Top elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ef80f9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#top\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm143.6 28.9l72.4-75.5V392c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24V209.4l72.4 75.5c9.3 9.7 24.8 9.9 34.3.4l10.9-11c9.4-9.4 9.4-24.6 0-33.9L273 107.7c-9.4-9.4-24.6-9.4-33.9 0L106.3 240.4c-9.4 9.4-9.4 24.6 0 33.9l10.9 11c9.6 9.5 25.1 9.3 34.4-.4z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Kulturwelten Sommerakademie 2026 Musikverein Wien6 &#8211; 11 July \u2669 \ud834\udd1e \u266b \ud834\udd22 \u266a \ud834\udd21 \u266c \ud834\udd1e \u266b \ud834\udd22 \u2669 \u266a Dozent:innen Akiko Nakajima, Gesang Maria Woldrich, Gesang Elena Copons-Labarias, Gesang Eszter Haffner, Violine &amp; Viola Dominika Falger, Violine Yair Kless, Violine Annelie Gahl, Violine Wladislaw Winokurow, Violine Regina Brandst\u00e4tter, Violine Andrei Kalisch, Violine Stanislaw Tichonow, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-24397","page","type-page","status-publish","hentry"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kulturwelten.at\/de\/wp-json\/wp\/v2\/pages\/24397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kulturwelten.at\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kulturwelten.at\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kulturwelten.at\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kulturwelten.at\/de\/wp-json\/wp\/v2\/comments?post=24397"}],"version-history":[{"count":7,"href":"https:\/\/www.kulturwelten.at\/de\/wp-json\/wp\/v2\/pages\/24397\/revisions"}],"predecessor-version":[{"id":26472,"href":"https:\/\/www.kulturwelten.at\/de\/wp-json\/wp\/v2\/pages\/24397\/revisions\/26472"}],"wp:attachment":[{"href":"https:\/\/www.kulturwelten.at\/de\/wp-json\/wp\/v2\/media?parent=24397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}